{"id":4418,"date":"2025-07-21T10:53:01","date_gmt":"2025-07-21T08:53:01","guid":{"rendered":"https:\/\/cebus-celle.de\/?page_id=4418"},"modified":"2025-08-11T14:06:56","modified_gmt":"2025-08-11T12:06:56","slug":"online-bestellung-rufmobil-celle","status":"publish","type":"page","link":"https:\/\/cebus-celle.de\/en\/mobilitaet\/rufmobil-celle\/online-bestellung-rufmobil-celle\/","title":{"rendered":"Online-Bestellung RufMobil Celle"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4418\" class=\"elementor elementor-4418\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fefce35 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"fefce35\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f64d76b\" data-id=\"f64d76b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a15875f elementor-widget elementor-widget-heading\" data-id=\"a15875f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ONLINE-BESTELLUNG: RUFMOBIL<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19ea24b elementor-widget elementor-widget-text-editor\" data-id=\"19ea24b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"72\" data-end=\"117\">Buche jetzt deine RufMobil-Fahrt online!<\/p><p data-start=\"119\" data-end=\"270\">Einfach App runterladen, registrieren und los geht\u2019s: Wunsch-Haltestelle und Abfahrtszeit eingeben \u2013 fertig! Dein RufMobil kommt dann p\u00fcnktlich zu dir.<\/p><p data-start=\"272\" data-end=\"328\" data-is-last-node=\"\" data-is-only-node=\"\">Wichtig: Bitte mindestens 59 Minuten vor Abfahrt buchen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8b8cd3f\" data-id=\"8b8cd3f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-e08a7fd e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"e08a7fd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e04e58f elementor-widget elementor-widget-heading\" data-id=\"e04e58f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Online-Buchung \u00fcber AnSaT<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c773f6 elementor-widget elementor-widget-html\" data-id=\"1c773f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe id=\"ansat_iframe\" src=\"https:\/\/ansat.kvg-bus.de\/BGCE\/AnsatPortalAuskunft\/\"border=\"0\" style=\"border: none;\" width=\"100%\" height=\"400\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a869cc e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"5a869cc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f26c0d elementor-widget elementor-widget-spacer\" data-id=\"7f26c0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35fed41 elementor-widget elementor-widget-theme-gravity-forms\" data-id=\"35fed41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-gravity-forms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script>\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gravity-theme gform-theme--no-framework' data-form-theme='gravity-theme' data-form-index='0' id='gform_wrapper_18' ><form method='post' enctype='multipart\/form-data'  id='gform_18'  action='\/en\/wp-json\/wp\/v2\/pages\/4418' data-formid='18' novalidate>\n                        <div class='gform-body gform_body'><div id='gform_fields_18' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_18_1\" class=\"gfield gfield--type-survey gfield--input-type-rating field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible gsurvey-survey-field \"  data-field-class=\"gsurvey-survey-field\" ><label class='gfield_label gform-field-label' >Wie gut gef\u00e4llt dir unsere Website?<\/label><div class='ginput_container gsurvey-rating-wrapper'><div class='gsurvey-rating' id='input_18_1'><input name='input_1' type='radio' value='grating172b515f7'  id='choice_18_1_0'    \/><label for='choice_18_1_0' title='Herausragend'><span>Herausragend<\/span><\/label><input name='input_1' type='radio' value='grating15b90bab7'  id='choice_18_1_1'    \/><label for='choice_18_1_1' title='Vorwiegend gut'><span>Vorwiegend gut<\/span><\/label><input name='input_1' type='radio' value='grating196111746'  id='choice_18_1_2'    \/><label for='choice_18_1_2' title='Neutral'><span>Neutral<\/span><\/label><input name='input_1' type='radio' value='grating112dfd37b'  id='choice_18_1_3'    \/><label for='choice_18_1_3' title='Nicht gut'><span>Nicht gut<\/span><\/label><input name='input_1' type='radio' value='grating16b0d9dde'  id='choice_18_1_4'    \/><label for='choice_18_1_4' title='Furchtbar'><span>Furchtbar<\/span><\/label><\/div><\/div><\/div><div id=\"field_18_5\" class=\"gfield gfield--type-website gfield--input-type-website gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_18_5'>Auf welcher Seite befindest du dich?<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Required)<\/span><\/span><\/label><div class='ginput_container ginput_container_website'>\n                    <input name='input_5' id='input_18_5' type='url' value='' class='large'    placeholder='https:\/\/' aria-required=\"true\" aria-invalid=\"false\" \/>\n                <\/div><\/div><div id=\"field_18_3\" class=\"gfield gfield--type-textarea gfield--input-type-textarea gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_18_3'>M\u00f6chtest du uns sonst noch etwas sagen?<\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_3' id='input_18_3' class='textarea small'      aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/div><\/div><\/div>\n        <div class='gform-footer gform_footer top_label'> <label><input type='submit' id='gform_submit_button_18' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='ABSENDEN'  \/><i aria-hidden=\"true\" class=\"fas fa-star\"><\/i><\/label> \n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_18' value='postback' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_18' id='gform_theme_18' value='gravity-theme' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_18' id='gform_style_settings_18' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_18' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='18' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='EUR' value='z91\/8cDYLfXQH08S7Sp9xov9hOuGYDhm1+tn9avCPrUIa6f02jRWLFGCOKyji9vnCYa88na7qrVhuKHnTxCTqMCxUpssUt8OYVyX4aQHvQJ6Ksw=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_18' value='WyJbXSIsImE4MzJjNWExNDY0ZGExN2FiMDkxMjhjY2JiZTUyOWU1Il0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_18' id='gform_target_page_number_18' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_18' id='gform_source_page_number_18' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <input type=\"hidden\" id=\"ct_checkjs_647bba344396e7c8170902bcf2e15551\" name=\"ct_checkjs\" value=\"0\" \/><script >setTimeout(function(){var ct_input_name = \"ct_checkjs_647bba344396e7c8170902bcf2e15551\";if (document.getElementById(ct_input_name) !== null) {var ct_input_value = document.getElementById(ct_input_name).value;document.getElementById(ct_input_name).value = document.getElementById(ct_input_name).value.replace(ct_input_value, '73d4bb3d65b7509bd89d75ae36c948a6cd7821584eef77d181261e2bb3dd6778');}}, 1000);<\/script><input\n                    class=\"apbct_special_field apbct_email_id__gravity_form\"\n                    name=\"apbct__email_id__gravity_form\"\n                    aria-label=\"apbct__label_id__gravity_form\"\n                    type=\"text\" size=\"30\" maxlength=\"200\" autocomplete=\"off\"\n                    value=\"\"\n                \/><input\n                    class=\"apbct_special_field apbct_email_id__elementor_form\"\n                    name=\"apbct__email_id__elementor_form\"\n                    aria-label=\"apbct__label_id__elementor_form\"\n                    type=\"text\" size=\"30\" maxlength=\"200\" autocomplete=\"off\"\n                    value=\"\"\n                \/><\/form>\n                        <\/div><script>\ngform.initializeOnLoaded( function() {gformInitSpinner( 18, 'https:\/\/cebus-celle.de\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_18').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_18');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_18').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_18').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_18').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_18').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/  }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_18').val();gformInitSpinner( 18, 'https:\/\/cebus-celle.de\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [18, current_page]);window['gf_submitting_18'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_18').replaceWith(confirmation_content);jQuery(document).trigger('gform_confirmation_loaded', [18]);window['gf_submitting_18'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_18').text());}else{jQuery('#gform_18').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"18\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_18\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_18\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_18\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 18, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} );\n<\/script>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e448f16 elementor-widget elementor-widget-spacer\" data-id=\"e448f16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>ONLINE-BESTELLUNG: RUFMOBIL Buche jetzt deine RufMobil-Fahrt online! Einfach App runterladen, registrieren und los geht\u2019s: Wunsch-Haltestelle und Abfahrtszeit eingeben \u2013 fertig! Dein RufMobil kommt dann p\u00fcnktlich zu dir. Wichtig: Bitte mindestens 59 Minuten vor Abfahrt buchen. Online-Buchung \u00fcber AnSaT Sie sehen gerade einen Platzhalterinhalt von Standard. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf den Button unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden. Inhalt entsperren Erforderlichen Service akzeptieren und Inhalte entsperren Weitere Informationen Wie gut gef\u00e4llt dir unsere Website?HerausragendVorwiegend gutNeutralNicht gutFurchtbarAuf welcher Seite befindest du dich?(erforderlich) M\u00f6chtest du uns sonst noch etwas sagen?CAPTCHA<\/p>","protected":false},"author":4,"featured_media":2708,"parent":4088,"menu_order":6,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4418","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Online-Bestellung RufMobil Celle - Cebus Celle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cebus-celle.de\/en\/mobility-2\/rufmobil-celle\/online-bestellung-rufmobil-celle\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Online-Bestellung RufMobil Celle - Cebus Celle\" \/>\n<meta property=\"og:description\" content=\"ONLINE-BESTELLUNG: RUFMOBIL Buche jetzt deine RufMobil-Fahrt online! Einfach App runterladen, registrieren und los geht\u2019s: Wunsch-Haltestelle und Abfahrtszeit eingeben \u2013 fertig! Dein RufMobil kommt dann p\u00fcnktlich zu dir. Wichtig: Bitte mindestens 59 Minuten vor Abfahrt buchen. Online-Buchung \u00fcber AnSaT Sie sehen gerade einen Platzhalterinhalt von Standard. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf den Button unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden. Inhalt entsperren Erforderlichen Service akzeptieren und Inhalte entsperren Weitere Informationen Wie gut gef\u00e4llt dir unsere Website?HerausragendVorwiegend gutNeutralNicht gutFurchtbarAuf welcher Seite befindest du dich?(erforderlich) M\u00f6chtest du uns sonst noch etwas sagen?CAPTCHA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cebus-celle.de\/en\/mobility-2\/rufmobil-celle\/online-bestellung-rufmobil-celle\/\" \/>\n<meta property=\"og:site_name\" content=\"Cebus Celle\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-11T12:06:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cebus-celle.de\/wp-content\/uploads\/Header-Subsite-RufMobil.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/mobilitaet\\\/rufmobil-celle\\\/online-bestellung-rufmobil-celle\\\/\",\"url\":\"https:\\\/\\\/cebus-celle.de\\\/mobilitaet\\\/rufmobil-celle\\\/online-bestellung-rufmobil-celle\\\/\",\"name\":\"Online-Bestellung RufMobil Celle - Cebus Celle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/mobilitaet\\\/rufmobil-celle\\\/online-bestellung-rufmobil-celle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/mobilitaet\\\/rufmobil-celle\\\/online-bestellung-rufmobil-celle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebus-celle.de\\\/wp-content\\\/uploads\\\/Header-Subsite-RufMobil.png\",\"datePublished\":\"2025-07-21T08:53:01+00:00\",\"dateModified\":\"2025-08-11T12:06:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/mobilitaet\\\/rufmobil-celle\\\/online-bestellung-rufmobil-celle\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cebus-celle.de\\\/mobilitaet\\\/rufmobil-celle\\\/online-bestellung-rufmobil-celle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/mobilitaet\\\/rufmobil-celle\\\/online-bestellung-rufmobil-celle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cebus-celle.de\\\/wp-content\\\/uploads\\\/Header-Subsite-RufMobil.png\",\"contentUrl\":\"https:\\\/\\\/cebus-celle.de\\\/wp-content\\\/uploads\\\/Header-Subsite-RufMobil.png\",\"width\":1920,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/mobilitaet\\\/rufmobil-celle\\\/online-bestellung-rufmobil-celle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cebus-celle.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mobilit\u00e4t\",\"item\":\"https:\\\/\\\/cebus-celle.de\\\/mobilitaet\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"RufMobil Celle\",\"item\":\"https:\\\/\\\/cebus-celle.de\\\/mobilitaet\\\/rufmobil-celle\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Online-Bestellung RufMobil Celle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/#website\",\"url\":\"https:\\\/\\\/cebus-celle.de\\\/\",\"name\":\"Cebus Celle\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cebus-celle.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/#organization\",\"name\":\"Cebus Celle\",\"url\":\"https:\\\/\\\/cebus-celle.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cebus-celle.de\\\/wp-content\\\/uploads\\\/logo-kvg.png\",\"contentUrl\":\"https:\\\/\\\/cebus-celle.de\\\/wp-content\\\/uploads\\\/logo-kvg.png\",\"width\":171,\"height\":68,\"caption\":\"Cebus Celle\"},\"image\":{\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Online-Bestellung RufMobil Celle - Cebus Celle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cebus-celle.de\/en\/mobility-2\/rufmobil-celle\/online-bestellung-rufmobil-celle\/","og_locale":"en_GB","og_type":"article","og_title":"Online-Bestellung RufMobil Celle - Cebus Celle","og_description":"ONLINE-BESTELLUNG: RUFMOBIL Buche jetzt deine RufMobil-Fahrt online! Einfach App runterladen, registrieren und los geht\u2019s: Wunsch-Haltestelle und Abfahrtszeit eingeben \u2013 fertig! Dein RufMobil kommt dann p\u00fcnktlich zu dir. Wichtig: Bitte mindestens 59 Minuten vor Abfahrt buchen. Online-Buchung \u00fcber AnSaT Sie sehen gerade einen Platzhalterinhalt von Standard. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf den Button unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden. Inhalt entsperren Erforderlichen Service akzeptieren und Inhalte entsperren Weitere Informationen Wie gut gef\u00e4llt dir unsere Website?HerausragendVorwiegend gutNeutralNicht gutFurchtbarAuf welcher Seite befindest du dich?(erforderlich) M\u00f6chtest du uns sonst noch etwas sagen?CAPTCHA","og_url":"https:\/\/cebus-celle.de\/en\/mobility-2\/rufmobil-celle\/online-bestellung-rufmobil-celle\/","og_site_name":"Cebus Celle","article_modified_time":"2025-08-11T12:06:56+00:00","og_image":[{"width":1920,"height":600,"url":"https:\/\/cebus-celle.de\/wp-content\/uploads\/Header-Subsite-RufMobil.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cebus-celle.de\/mobilitaet\/rufmobil-celle\/online-bestellung-rufmobil-celle\/","url":"https:\/\/cebus-celle.de\/mobilitaet\/rufmobil-celle\/online-bestellung-rufmobil-celle\/","name":"Online-Bestellung RufMobil Celle - Cebus Celle","isPartOf":{"@id":"https:\/\/cebus-celle.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cebus-celle.de\/mobilitaet\/rufmobil-celle\/online-bestellung-rufmobil-celle\/#primaryimage"},"image":{"@id":"https:\/\/cebus-celle.de\/mobilitaet\/rufmobil-celle\/online-bestellung-rufmobil-celle\/#primaryimage"},"thumbnailUrl":"https:\/\/cebus-celle.de\/wp-content\/uploads\/Header-Subsite-RufMobil.png","datePublished":"2025-07-21T08:53:01+00:00","dateModified":"2025-08-11T12:06:56+00:00","breadcrumb":{"@id":"https:\/\/cebus-celle.de\/mobilitaet\/rufmobil-celle\/online-bestellung-rufmobil-celle\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cebus-celle.de\/mobilitaet\/rufmobil-celle\/online-bestellung-rufmobil-celle\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cebus-celle.de\/mobilitaet\/rufmobil-celle\/online-bestellung-rufmobil-celle\/#primaryimage","url":"https:\/\/cebus-celle.de\/wp-content\/uploads\/Header-Subsite-RufMobil.png","contentUrl":"https:\/\/cebus-celle.de\/wp-content\/uploads\/Header-Subsite-RufMobil.png","width":1920,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/cebus-celle.de\/mobilitaet\/rufmobil-celle\/online-bestellung-rufmobil-celle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cebus-celle.de\/"},{"@type":"ListItem","position":2,"name":"Mobilit\u00e4t","item":"https:\/\/cebus-celle.de\/mobilitaet\/"},{"@type":"ListItem","position":3,"name":"RufMobil Celle","item":"https:\/\/cebus-celle.de\/mobilitaet\/rufmobil-celle\/"},{"@type":"ListItem","position":4,"name":"Online-Bestellung RufMobil Celle"}]},{"@type":"WebSite","@id":"https:\/\/cebus-celle.de\/#website","url":"https:\/\/cebus-celle.de\/","name":"Cebus Celle","description":"","publisher":{"@id":"https:\/\/cebus-celle.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cebus-celle.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/cebus-celle.de\/#organization","name":"Cebus Celle","url":"https:\/\/cebus-celle.de\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cebus-celle.de\/#\/schema\/logo\/image\/","url":"https:\/\/cebus-celle.de\/wp-content\/uploads\/logo-kvg.png","contentUrl":"https:\/\/cebus-celle.de\/wp-content\/uploads\/logo-kvg.png","width":171,"height":68,"caption":"Cebus Celle"},"image":{"@id":"https:\/\/cebus-celle.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cebus-celle.de\/en\/wp-json\/wp\/v2\/pages\/4418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cebus-celle.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cebus-celle.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cebus-celle.de\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/cebus-celle.de\/en\/wp-json\/wp\/v2\/comments?post=4418"}],"version-history":[{"count":19,"href":"https:\/\/cebus-celle.de\/en\/wp-json\/wp\/v2\/pages\/4418\/revisions"}],"predecessor-version":[{"id":4638,"href":"https:\/\/cebus-celle.de\/en\/wp-json\/wp\/v2\/pages\/4418\/revisions\/4638"}],"up":[{"embeddable":true,"href":"https:\/\/cebus-celle.de\/en\/wp-json\/wp\/v2\/pages\/4088"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cebus-celle.de\/en\/wp-json\/wp\/v2\/media\/2708"}],"wp:attachment":[{"href":"https:\/\/cebus-celle.de\/en\/wp-json\/wp\/v2\/media?parent=4418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}