{"id":6492,"date":"2026-08-31T15:42:51","date_gmt":"2026-08-31T13:42:51","guid":{"rendered":"https:\/\/cebus-celle.de\/?p=6492"},"modified":"2026-08-31T15:42:51","modified_gmt":"2026-08-31T13:42:51","slug":"rufmobil-app-aktualisieren-version-6-0-1-erforderlich","status":"publish","type":"post","link":"https:\/\/cebus-celle.de\/es\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\/","title":{"rendered":"RufMobil-App aktualisieren: Version 6.0.1 erforderlich"},"content":{"rendered":"<h2>RufMobil-App aktualisieren: Version 6.0.1 erforderlich<\/h2>\n<p>Du m\u00f6chtest eine Fahrt mit dem RufMobil buchen? Dann pr\u00fcfe bitte, ob du die aktuelle Version unserer RufMobil-App installiert hast.<\/p>\n<p>F\u00fcr Buchungen ist die <strong>App-Version 6.0.1<\/strong> erforderlich. Mit einer \u00e4lteren Version k\u00f6nnen keine Buchungen vorgenommen werden.<\/p>\n<p><strong>Bitte beachten:<\/strong> En <strong>Linie 660 kann derzeit nicht \u00fcber die RufMobil-App gebucht werden.<\/strong><\/p>\n<p>\u00d6ffne den App-Store auf deinem Smartphone, suche nach der RufMobil-App und f\u00fchre das verf\u00fcgbare Update durch. Anschlie\u00dfend kannst du deine RufMobil-Fahrten wie gewohnt \u00fcber die App buchen.<\/p>\n<p>Unser Tipp: Aktualisiere die App am besten direkt, damit du bei deiner n\u00e4chsten Buchung startklar bist.<\/p>","protected":false},"excerpt":{"rendered":"<p>RufMobil-App aktualisieren: Version 6.0.1 erforderlich Du m\u00f6chtest eine Fahrt mit dem RufMobil buchen? Dann pr\u00fcfe bitte, ob du die aktuelle Version unserer RufMobil-App installiert hast. F\u00fcr Buchungen ist die App-Version 6.0.1 erforderlich. Mit einer \u00e4lteren Version k\u00f6nnen keine Buchungen vorgenommen werden. Bitte beachten: Die Linie 660 kann derzeit nicht \u00fcber die RufMobil-App gebucht werden. \u00d6ffne den App-Store auf deinem Smartphone, suche nach der RufMobil-App und f\u00fchre das verf\u00fcgbare Update durch. Anschlie\u00dfend kannst du deine RufMobil-Fahrten wie gewohnt \u00fcber die App buchen. Unser Tipp: Aktualisiere die App am besten direkt, damit du bei deiner n\u00e4chsten Buchung startklar bist.<\/p>","protected":false},"author":4,"featured_media":2708,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RufMobil-App aktualisieren: Version 6.0.1 erforderlich - Cebus Celle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cebus-celle.de\/es\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RufMobil-App aktualisieren: Version 6.0.1 erforderlich - Cebus Celle\" \/>\n<meta property=\"og:description\" content=\"RufMobil-App aktualisieren: Version 6.0.1 erforderlich Du m\u00f6chtest eine Fahrt mit dem RufMobil buchen? Dann pr\u00fcfe bitte, ob du die aktuelle Version unserer RufMobil-App installiert hast. F\u00fcr Buchungen ist die App-Version 6.0.1 erforderlich. Mit einer \u00e4lteren Version k\u00f6nnen keine Buchungen vorgenommen werden. Bitte beachten: Die Linie 660 kann derzeit nicht \u00fcber die RufMobil-App gebucht werden. \u00d6ffne den App-Store auf deinem Smartphone, suche nach der RufMobil-App und f\u00fchre das verf\u00fcgbare Update durch. Anschlie\u00dfend kannst du deine RufMobil-Fahrten wie gewohnt \u00fcber die App buchen. Unser Tipp: Aktualisiere die App am besten direkt, damit du bei deiner n\u00e4chsten Buchung startklar bist.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cebus-celle.de\/es\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\/\" \/>\n<meta property=\"og:site_name\" content=\"Cebus Celle\" \/>\n<meta property=\"article:published_time\" content=\"2026-08-31T13:42:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cebus-celle.de\/wp-content\/uploads\/Header-Subsite-RufMobil.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"sprager\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"sprager\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\\\/\"},\"author\":{\"name\":\"sprager\",\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/#\\\/schema\\\/person\\\/2795ac9a3db362efb388f5d648e603ae\"},\"headline\":\"RufMobil-App aktualisieren: Version 6.0.1 erforderlich\",\"datePublished\":\"2026-08-31T13:42:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\\\/\"},\"wordCount\":106,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebus-celle.de\\\/wp-content\\\/uploads\\\/Header-Subsite-RufMobil.png\",\"articleSection\":[\"News\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cebus-celle.de\\\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\\\/\",\"url\":\"https:\\\/\\\/cebus-celle.de\\\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\\\/\",\"name\":\"RufMobil-App aktualisieren: Version 6.0.1 erforderlich - Cebus Celle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebus-celle.de\\\/wp-content\\\/uploads\\\/Header-Subsite-RufMobil.png\",\"datePublished\":\"2026-08-31T13:42:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cebus-celle.de\\\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cebus-celle.de\\\/wp-content\\\/uploads\\\/Header-Subsite-RufMobil.png\",\"contentUrl\":\"https:\\\/\\\/cebus-celle.de\\\/wp-content\\\/uploads\\\/Header-Subsite-RufMobil.png\",\"width\":1920,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cebus-celle.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RufMobil-App aktualisieren: Version 6.0.1 erforderlich\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/#website\",\"url\":\"https:\\\/\\\/cebus-celle.de\\\/\",\"name\":\"Cebus Celle\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cebus-celle.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/#organization\",\"name\":\"Cebus Celle\",\"url\":\"https:\\\/\\\/cebus-celle.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cebus-celle.de\\\/wp-content\\\/uploads\\\/logo-kvg.png\",\"contentUrl\":\"https:\\\/\\\/cebus-celle.de\\\/wp-content\\\/uploads\\\/logo-kvg.png\",\"width\":171,\"height\":68,\"caption\":\"Cebus Celle\"},\"image\":{\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cebus-celle.de\\\/#\\\/schema\\\/person\\\/2795ac9a3db362efb388f5d648e603ae\",\"name\":\"sprager\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c9f4904d5ee6846a305eba03c67dfde589dc71ebb212f17ea973f97cbdd5f980?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c9f4904d5ee6846a305eba03c67dfde589dc71ebb212f17ea973f97cbdd5f980?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c9f4904d5ee6846a305eba03c67dfde589dc71ebb212f17ea973f97cbdd5f980?s=96&d=mm&r=g\",\"caption\":\"sprager\"},\"url\":\"https:\\\/\\\/cebus-celle.de\\\/es\\\/author\\\/sprager\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RufMobil-App aktualisieren: Version 6.0.1 erforderlich - Cebus Celle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cebus-celle.de\/es\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\/","og_locale":"es_ES","og_type":"article","og_title":"RufMobil-App aktualisieren: Version 6.0.1 erforderlich - Cebus Celle","og_description":"RufMobil-App aktualisieren: Version 6.0.1 erforderlich Du m\u00f6chtest eine Fahrt mit dem RufMobil buchen? Dann pr\u00fcfe bitte, ob du die aktuelle Version unserer RufMobil-App installiert hast. F\u00fcr Buchungen ist die App-Version 6.0.1 erforderlich. Mit einer \u00e4lteren Version k\u00f6nnen keine Buchungen vorgenommen werden. Bitte beachten: Die Linie 660 kann derzeit nicht \u00fcber die RufMobil-App gebucht werden. \u00d6ffne den App-Store auf deinem Smartphone, suche nach der RufMobil-App und f\u00fchre das verf\u00fcgbare Update durch. Anschlie\u00dfend kannst du deine RufMobil-Fahrten wie gewohnt \u00fcber die App buchen. Unser Tipp: Aktualisiere die App am besten direkt, damit du bei deiner n\u00e4chsten Buchung startklar bist.","og_url":"https:\/\/cebus-celle.de\/es\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\/","og_site_name":"Cebus Celle","article_published_time":"2026-08-31T13:42:51+00:00","og_image":[{"width":1920,"height":600,"url":"https:\/\/cebus-celle.de\/wp-content\/uploads\/Header-Subsite-RufMobil.png","type":"image\/png"}],"author":"sprager","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"sprager","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cebus-celle.de\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\/#article","isPartOf":{"@id":"https:\/\/cebus-celle.de\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\/"},"author":{"name":"sprager","@id":"https:\/\/cebus-celle.de\/#\/schema\/person\/2795ac9a3db362efb388f5d648e603ae"},"headline":"RufMobil-App aktualisieren: Version 6.0.1 erforderlich","datePublished":"2026-08-31T13:42:51+00:00","mainEntityOfPage":{"@id":"https:\/\/cebus-celle.de\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\/"},"wordCount":106,"commentCount":0,"publisher":{"@id":"https:\/\/cebus-celle.de\/#organization"},"image":{"@id":"https:\/\/cebus-celle.de\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\/#primaryimage"},"thumbnailUrl":"https:\/\/cebus-celle.de\/wp-content\/uploads\/Header-Subsite-RufMobil.png","articleSection":["News"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cebus-celle.de\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cebus-celle.de\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\/","url":"https:\/\/cebus-celle.de\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\/","name":"RufMobil-App aktualisieren: Version 6.0.1 erforderlich - Cebus Celle","isPartOf":{"@id":"https:\/\/cebus-celle.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cebus-celle.de\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\/#primaryimage"},"image":{"@id":"https:\/\/cebus-celle.de\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\/#primaryimage"},"thumbnailUrl":"https:\/\/cebus-celle.de\/wp-content\/uploads\/Header-Subsite-RufMobil.png","datePublished":"2026-08-31T13:42:51+00:00","breadcrumb":{"@id":"https:\/\/cebus-celle.de\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cebus-celle.de\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cebus-celle.de\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\/#primaryimage","url":"https:\/\/cebus-celle.de\/wp-content\/uploads\/Header-Subsite-RufMobil.png","contentUrl":"https:\/\/cebus-celle.de\/wp-content\/uploads\/Header-Subsite-RufMobil.png","width":1920,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/cebus-celle.de\/rufmobil-app-aktualisieren-version-6-0-1-erforderlich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cebus-celle.de\/"},{"@type":"ListItem","position":2,"name":"RufMobil-App aktualisieren: Version 6.0.1 erforderlich"}]},{"@type":"WebSite","@id":"https:\/\/cebus-celle.de\/#website","url":"https:\/\/cebus-celle.de\/","name":"Cebus Celle","description":"","publisher":{"@id":"https:\/\/cebus-celle.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cebus-celle.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cebus-celle.de\/#organization","name":"Cebus Celle","url":"https:\/\/cebus-celle.de\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cebus-celle.de\/#\/schema\/logo\/image\/","url":"https:\/\/cebus-celle.de\/wp-content\/uploads\/logo-kvg.png","contentUrl":"https:\/\/cebus-celle.de\/wp-content\/uploads\/logo-kvg.png","width":171,"height":68,"caption":"Cebus Celle"},"image":{"@id":"https:\/\/cebus-celle.de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cebus-celle.de\/#\/schema\/person\/2795ac9a3db362efb388f5d648e603ae","name":"sprager","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c9f4904d5ee6846a305eba03c67dfde589dc71ebb212f17ea973f97cbdd5f980?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c9f4904d5ee6846a305eba03c67dfde589dc71ebb212f17ea973f97cbdd5f980?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c9f4904d5ee6846a305eba03c67dfde589dc71ebb212f17ea973f97cbdd5f980?s=96&d=mm&r=g","caption":"sprager"},"url":"https:\/\/cebus-celle.de\/es\/author\/sprager\/"}]}},"_links":{"self":[{"href":"https:\/\/cebus-celle.de\/es\/wp-json\/wp\/v2\/posts\/6492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cebus-celle.de\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cebus-celle.de\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cebus-celle.de\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/cebus-celle.de\/es\/wp-json\/wp\/v2\/comments?post=6492"}],"version-history":[{"count":1,"href":"https:\/\/cebus-celle.de\/es\/wp-json\/wp\/v2\/posts\/6492\/revisions"}],"predecessor-version":[{"id":6493,"href":"https:\/\/cebus-celle.de\/es\/wp-json\/wp\/v2\/posts\/6492\/revisions\/6493"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cebus-celle.de\/es\/wp-json\/wp\/v2\/media\/2708"}],"wp:attachment":[{"href":"https:\/\/cebus-celle.de\/es\/wp-json\/wp\/v2\/media?parent=6492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cebus-celle.de\/es\/wp-json\/wp\/v2\/categories?post=6492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cebus-celle.de\/es\/wp-json\/wp\/v2\/tags?post=6492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}